{"id":142,"date":"2024-06-19T06:21:57","date_gmt":"2024-06-19T04:21:57","guid":{"rendered":"https:\/\/digitnow.com.mx\/?page_id=142"},"modified":"2026-03-05T21:31:22","modified_gmt":"2026-03-06T03:31:22","slug":"cursos","status":"publish","type":"page","link":"https:\/\/digitnow.com.mx\/en\/servicios-2\/cursos\/","title":{"rendered":"Business Training"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"142\" class=\"elementor elementor-142\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-429dc344 e-flex e-con-boxed e-con e-parent\" data-id=\"429dc344\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/vid-cdn.multiscreensite.com\\\/b76b5c70\\\/videos\\\/7hECnYNIRXGrIwbsGSHV_big-data-cloud-computing-using-artificial-intellig-KQY24AX-v.mp4&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container elementor-hidden-mobile\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-64e2e05a elementor-widget elementor-widget-heading\" data-id=\"64e2e05a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conozca nuestros Cursos y planes de Capacitaci\u00f3n Empresarial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d63bd52 e-flex e-con-boxed e-con e-parent\" data-id=\"d63bd52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b85f63 elementor-widget elementor-widget-text-editor\" data-id=\"1b85f63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">En<\/span> <strong>Digitnow<\/strong><span style=\"color: #000000;\">, ofrecemos<\/span> <strong>Capacitaci\u00f3n Empresarial<\/strong> <span style=\"color: #000000;\">con un enfoque personalizado para impulsar el crecimiento de su equipo. Nuestros<\/span> <strong>Cursos a la Medida<\/strong> <span style=\"color: #000000;\">y<\/span> <strong>Cursos por Aplicaci\u00f3n<\/strong><span style=\"color: #000000;\"> est\u00e1n dise\u00f1ados para satisfacer las necesidades espec\u00edficas de su empresa, asegurando que su personal adquiera las competencias necesarias para enfrentar los desaf\u00edos actuales del mercado.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57f7904 e-grid e-con-boxed e-con e-parent\" data-id=\"57f7904\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-85cc641 e-con-full e-flex e-con e-child\" data-id=\"85cc641\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4e1bc9 elementor-widget elementor-widget-image\" data-id=\"e4e1bc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-1024x1024.png\" class=\"attachment-large size-large wp-image-3629\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-1024x1024.png 1024w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-300x300.png 300w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-150x150.png 150w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-768x768.png 768w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-12x12.png 12w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fff5507 elementor-widget elementor-widget-heading\" data-id=\"fff5507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cursos Remotos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d900e7 elementor-widget elementor-widget-text-editor\" data-id=\"0d900e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestros cursos son remotos y grabados, siempre tendr\u00e1 apoyo de un especialista certificado que estar\u00e1 gui\u00e1ndolo para lograr sus objetivos planteados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a3219a e-con-full e-flex e-con e-child\" data-id=\"6a3219a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3c7f29 elementor-widget elementor-widget-image\" data-id=\"d3c7f29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/productividad-2-1024x1024.png\" class=\"attachment-large size-large wp-image-3625\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/productividad-2-1024x1024.png 1024w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/productividad-2-300x300.png 300w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/productividad-2-150x150.png 150w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/productividad-2-768x768.png 768w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/productividad-2-12x12.png 12w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/productividad-2.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5895cf elementor-widget elementor-widget-heading\" data-id=\"c5895cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Personalizaci\u00f3n de Contenidos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33c1644 elementor-widget elementor-widget-text-editor\" data-id=\"33c1644\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A\u00fan y cuando tenemos cursos de tecnolog\u00eda con contenido predefinido, podemos ajustarlo a sus necesidades de negocio para agregar valor y puedan hacer realidad los proyectos planificados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a76cc45 e-con-full e-flex e-con e-child\" data-id=\"a76cc45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97bfde7 elementor-widget elementor-widget-image\" data-id=\"97bfde7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/servicio-clientes-1024x1024.png\" class=\"attachment-large size-large wp-image-3614\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/servicio-clientes-1024x1024.png 1024w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/servicio-clientes-300x300.png 300w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/servicio-clientes-150x150.png 150w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/servicio-clientes-768x768.png 768w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/servicio-clientes-12x12.png 12w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/servicio-clientes.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-249d702 elementor-widget elementor-widget-heading\" data-id=\"249d702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cursos Totalmente Pr\u00e1cticos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e90786b elementor-widget elementor-widget-text-editor\" data-id=\"e90786b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Todos nuestros cursos cuentan con recursos y materiales de trabajo oficiales que son totalmente pr\u00e1cticos y puedan simular casos reales que ocurren en el d\u00eda a d\u00eda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d33c93 e-flex e-con-boxed e-con e-parent\" data-id=\"8d33c93\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6376c1 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f6376c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/digitnow.com.mx\/cursos-a-la-medida\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cursos a la medida<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-242b12b elementor-widget elementor-widget-heading\" data-id=\"242b12b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aprenda m\u00e1s de nuestros cursos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-964ee70 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"964ee70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/digitnow.com.mx\/cursos-por-aplicacion\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cursos por aplicaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3646afc e-flex e-con-boxed e-con e-parent\" data-id=\"3646afc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a328d3b e-con-full e-flex e-con e-child\" data-id=\"a328d3b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-508ca70 elementor-widget elementor-widget-heading\" data-id=\"508ca70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Todos los cursos que necesita,\ntodos en un solo lugar.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4a14aa elementor-widget elementor-widget-text-editor\" data-id=\"e4a14aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"1678135233\" class=\"u_1678135233 dmNewParagraph\" data-version=\"5\"><p style=\"text-align: center;\">Ofrecemos una amplia gama de cursos en tecnolog\u00eda para satisfacer cualquier tipo de necesidad.<\/p><\/div><div id=\"1446662093\" class=\"u_1446662093 dmNewParagraph\" data-version=\"5\"><p style=\"text-align: left;\">En todos nuestros cursos contar\u00e1 con el apoyo de instructor capacitado con y con el valor agregado que solo Digitnow Puede ofrecerle:<\/p><p style=\"text-align: left;\">\u2022 Tendr\u00e1 material oficial y de uso para que practique.<\/p><p class=\"text-align-justify\" style=\"text-align: left;\">\u2022 Tiempo extra de asesor\u00eda offline para resolver tus dudas al finalizar cada curso.<\/p><p style=\"text-align: left;\">\u2022 Aprender\u00e1 metodolog\u00edas de proyectos con material para trabajo en las sesiones.<\/p><p style=\"text-align: left;\">\u2022 Se graban las sesiones para ser consultadas cuando usted requiera.<\/p><p style=\"text-align: left;\">\u2022 Se entrega constancia con firma de instructor certificado.<\/p><p style=\"text-align: left;\">\u2022 Estar\u00e1 listo para usar el aprendizaje al momento.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f67271b elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f67271b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/digitnow.com.mx\/es_mx\/contacto\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0bc8113 e-con-full e-flex e-con e-child\" data-id=\"0bc8113\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecbe426 elementor-widget elementor-widget-image-carousel\" data-id=\"ecbe426\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/cursos-digitnow-1-1024x1024.png\" alt=\"cursos digitnow\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/curss2-640w.webp\" alt=\"curss2-640w\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/cuadrado1-640w.webp\" alt=\"cuadrado1-640w\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/ejecutivoExcel-640w.webp\" alt=\"ejecutivoExcel-640w\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/businessman-using-a-computer-talking-on-the-mobile-phone-640w.webp\" alt=\"businessman-using-a-computer-talking-on-the-mobile-phone-640w\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/Laptop-with-Glasses-and-Notebook-640w.webp\" alt=\"Laptop-with-Glasses-and-Notebook-640w\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ea67fd8 e-flex e-con-boxed e-con e-parent\" data-id=\"4ea67fd8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-241a057d elementor-widget elementor-widget-heading\" data-id=\"241a057d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cat\u00e1logo de nuestros cursos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8af4c6 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"a8af4c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"176878790\" aria-label=\"Pesta\u00f1as. Abre elementos con Intro o Espacio, ci\u00e9rralos con Escape y navega con las fechas.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1768787901\" data-tab-title-id=\"e-n-tab-title-1768787901\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1768787901\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tMicrosoft 365\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1768787902\" data-tab-title-id=\"e-n-tab-title-1768787902\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1768787902\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tExcel\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1768787903\" data-tab-title-id=\"e-n-tab-title-1768787903\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1768787903\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tPower BI\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1768787904\" data-tab-title-id=\"e-n-tab-title-1768787904\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1768787904\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tSQL Server\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1768787905\" data-tab-title-id=\"e-n-tab-title-1768787905\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1768787905\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tAzure\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1768787901\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1768787901\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-40ec5ceb e-con-full e-flex e-con e-child\" data-id=\"40ec5ceb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-49f139fd e-grid e-con-boxed e-con e-child\" data-id=\"49f139fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39df0f35 elementor-widget elementor-widget-image\" data-id=\"39df0f35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"466\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/20-1024x597.webp\" class=\"attachment-large size-large wp-image-2457\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/20-1024x597.webp 1024w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/20-300x175.webp 300w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/20-768x448.webp 768w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/20.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25b801b7 e-flex e-con-boxed e-con e-child\" data-id=\"25b801b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f5c775f elementor-widget elementor-widget-heading\" data-id=\"2f5c775f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Curso Microsoft 365<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c2dc2ae elementor-widget elementor-widget-text-editor\" data-id=\"5c2dc2ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"rteBlock\" style=\"text-align: center;\">Hoy en d\u00eda el uso de las herramientas de ofim\u00e1tica se ha convertido en algo cotidiano, ya que estas son utilizadas en la escuela, en la oficina y hasta en casa. Por este motivo es tan necesario dominarlas ampliamente.<br \/>Le invitamos a participar de manera activa en este curso, para obtener las habilidades y conocimientos para editar documentos en Word u hojas de c\u00e1lculo en Excel, tambi\u00e9n ser\u00e1 capaz de realizar presentaciones en PowerPoint, integrando a la vez el Internet en el trabajo colaborativo.<br \/>Tenemos la capacidad de poder ajustar este entrenamiento para diferentes niveles desde b\u00e1sico hasta experto, personalizando el contenido para que aprenda lo que necesita para su negocio o empresa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32b249c0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"32b249c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/digitnow.com.mx\/es_mx\/cursos-microsoft-365\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Quiero saber m\u00e1s!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1768787902\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1768787902\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-23024310 e-con-full e-flex e-con e-child\" data-id=\"23024310\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3dc64150 e-grid e-con-boxed e-con e-child\" data-id=\"3dc64150\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ece6b7b elementor-widget elementor-widget-image\" data-id=\"4ece6b7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"552\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/curso-excel-eff76bd8-640w.webp\" class=\"attachment-large size-large wp-image-422\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/curso-excel-eff76bd8-640w.webp 640w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/curso-excel-eff76bd8-640w-300x259.webp 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-696edc4c e-flex e-con-boxed e-con e-child\" data-id=\"696edc4c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-308bce98 elementor-widget elementor-widget-heading\" data-id=\"308bce98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Curso Microsoft Excel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-185c32f6 elementor-widget elementor-widget-text-editor\" data-id=\"185c32f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"rteBlock\">Microsoft Excel, es un programa con el que puede realizar todo tipo de operaciones matem\u00e1ticas mediante hojas de c\u00e1lculo. Tambi\u00e9n se pueden crear tablas con las que combinar datos y poder realizar diferentes acciones. Se trata de una herramienta muy completa y que se puede aplicar en muchos \u00e1mbitos. Por eso, es por lo que es solicitada y es un parteaguas en la demanda por las empresas, por eso es importante que presuma sus conocimientos sobre esta aplicaci\u00f3n.<\/p>\n<p><\/p>\n<p class=\"rteBlock\">Contamos con cursos especializados para nivel b\u00e1sico o preparaci\u00f3n para niveles mas avanzados MOS (Microsoft Office Specialist) ya sea en nivel Associate (intermedio+) y Expert (nivel Avanzado).<\/p>\n<p><\/p>\n<p class=\"rteBlock\">Al igual que todos nuestros cursos, podemos personalizar el contenido seg\u00fan sus requerimientos organizacionales para agregarle mayor valor a su empresa y puedan utilizar los conocimientos cuanto antes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b2869af elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1b2869af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/digitnow.com.mx\/es_mx\/cursos-excel\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Quiero saber m\u00e1s!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1768787903\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1768787903\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-14534330 e-con-full e-flex e-con e-child\" data-id=\"14534330\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3a530b1d e-grid e-con-boxed e-con e-child\" data-id=\"3a530b1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-539d65a9 elementor-widget elementor-widget-image\" data-id=\"539d65a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"715\" height=\"482\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/Logo-Power-BI.png\" class=\"attachment-large size-large wp-image-2460\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/Logo-Power-BI.png 715w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/Logo-Power-BI-300x202.png 300w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/Logo-Power-BI-18x12.png 18w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5efa82a5 e-flex e-con-boxed e-con e-child\" data-id=\"5efa82a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18b7dd96 elementor-widget elementor-widget-heading\" data-id=\"18b7dd96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Curso Power BI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dfdb66d elementor-widget elementor-widget-text-editor\" data-id=\"4dfdb66d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"rteBlock\">Power BI es una herramienta de informes de BI basada en modelos de datos. Una herramienta l\u00edder y las m\u00e1s poderosa por estar en la nube y tener las capacidades de multiconexi\u00f3n, integraci\u00f3n con diferentes plataformas, enlace con lenguajes de programaci\u00f3n como R y Python, adem\u00e1s conexi\u00f3n con bases de datos. Adem\u00e1s, cuenta con su propio lenguaje de expresiones para an\u00e1lisis (DAX).<\/p>\n<p><\/p>\n<p class=\"rteBlock\">Con nuestros cursos puede aprender a:<\/p>\n<ul class=\"rteBlock defaultList\">\n<li>Gestionar grandes cantidades de datos<\/li>\n<li>Crear tableros de control para tener su informaci\u00f3n visual para la toma asertiva de decisiones.<\/li>\n<li>Inteligencia de negocios a su m\u00e1ximo esplendor<\/li>\n<li>Seguimiento a indicadores de desempe\u00f1o (KPI&#8217;s) tanto de su empresa\/negocio o del personal.<\/li>\n<li>Seguridad y control de accesibilidad para su informaci\u00f3n tanto interna como externa.<\/li>\n<li>An\u00e1lisis de datos para detectar tendencias valiosas y realizar predicciones informadas.<\/li>\n<li>Uso de lenguaje R como apoyo para sus predicciones de negocio y planeaciones estrat\u00e9gicas.<\/li>\n<li>Aprendizaje pr\u00e1ctico de mediciones (measures) para realizar c\u00e1lculos complejos mediante funciones.<\/li>\n<\/ul><div><br><\/div>\n<p class=\"rteBlock\">Si desea saber m\u00e1s, puede reservar con nosotros una cita para apoyarle y definir un programa personalizado que se adecue a sus necesidades.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-755d0ada elementor-align-center elementor-widget elementor-widget-button\" data-id=\"755d0ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/digitnow.com.mx\/es_mx\/cursos-power-bi\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Quiero saber m\u00e1s!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1768787904\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1768787904\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\" elementor-element elementor-element-c0e428 e-con-full e-flex e-con e-child\" data-id=\"c0e428\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1ea03651 e-grid e-con-boxed e-con e-child\" data-id=\"1ea03651\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60c64c6f elementor-widget elementor-widget-image\" data-id=\"60c64c6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"468\" height=\"421\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/Captura-de-pantalla-2024-06-24-010939.png\" class=\"attachment-large size-large wp-image-424\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/Captura-de-pantalla-2024-06-24-010939.png 468w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/Captura-de-pantalla-2024-06-24-010939-300x270.png 300w\" sizes=\"(max-width: 468px) 100vw, 468px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41211fea e-flex e-con-boxed e-con e-child\" data-id=\"41211fea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c05f2c4 elementor-widget elementor-widget-heading\" data-id=\"2c05f2c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Curso de an\u00e1lisis de informaci\u00f3n con SQL Server<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ece4a elementor-widget elementor-widget-text-editor\" data-id=\"19ece4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"rteBlock\">Microsoft\u00ae SQL Server\u00ae es el sistema gestor de bases de datos estructuradas l\u00edder en el mercado; , eficaz y confiable que ofrece un almac\u00e9n de datos completo y confiable.<\/p><p>\u00a0<\/p><p class=\"rteBlock\">Usted va a aprender en este curso:<\/p><ul class=\"rteBlock defaultList\"><li>Instalaci\u00f3n y configuraci\u00f3n.<\/li><li>Utilizar funciones y f\u00f3rmulas para crear c\u00e1lculos, tablas, vistas.<\/li><li>Conexiones a otras ases de datos.<\/li><li>Modelado de datos.<\/li><li>Aprender a diferenciar entre productos.<\/li><li>Crear reportes con inteligencia de negocios.<\/li><li>Procesamiento de consultas inteligentes.<\/li><li>Supervisi\u00f3n de bases de datos.<\/li><li>Creaci\u00f3n de roles.<\/li><li>Supervisi\u00f3n de bases de datos y seguridad.<\/li><\/ul><p>\u00a0<\/p><p class=\"rteBlock\">En Digitnow, estamos comprometidos con lograr que nuestros clientes puedan explotar al m\u00e1ximo sus licencias y recursos. Si desea mas informaci\u00f3n, no dude en contactarnos para entender sus necesidades y as\u00ed, poder crearle un programa a la medida.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbd1a00 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cbd1a00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/digitnow.com.mx\/es_mx\/cursos-sql-server\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Quiero saber m\u00e1s!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1768787905\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1768787905\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\" elementor-element elementor-element-78160642 e-con-full e-flex e-con e-child\" data-id=\"78160642\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2a3619a2 e-grid e-con-boxed e-con e-child\" data-id=\"2a3619a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-590f4f19 elementor-widget elementor-widget-image\" data-id=\"590f4f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"350\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/curso-en-linea-de-introduccion-a-microsoft-azure.jpg\" class=\"attachment-large size-large wp-image-2458\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/curso-en-linea-de-introduccion-a-microsoft-azure.jpg 560w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/curso-en-linea-de-introduccion-a-microsoft-azure-300x188.jpg 300w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/curso-en-linea-de-introduccion-a-microsoft-azure-18x12.jpg 18w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d246653 e-flex e-con-boxed e-con e-child\" data-id=\"3d246653\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22cd782f elementor-widget elementor-widget-heading\" data-id=\"22cd782f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Curso de fundamentos de Azure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a2ebca3 elementor-widget elementor-widget-text-editor\" data-id=\"4a2ebca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"rteBlock\">\u00bfEst\u00e1 interesado en la nube, pero no est\u00e1 seguro de c\u00f3mo puede ayudarle?&nbsp;<\/p><p class=\"rteBlock\">En este curso, descubrir\u00e1 las ventajas de usar los servicios de inform\u00e1tica en la nube y las diferencias entre los distintos tipos y categor\u00edas de inform\u00e1tica en la nube.<\/p>\n<p class=\"rteBlock\">Despu\u00e9s de completar este m\u00f3dulo, podr\u00e1:<\/p>\n<ul class=\"rteBlock defaultList\">\n<li>Elegir la tecnolog\u00eda de inform\u00e1tica sin servidor adecuada para su escenario empresarial.<\/li>\n<li>Identificar las ventajas y las consideraciones de los servicios en la nube.<\/li>\n<li>Describir las diferencias que hay entre las categor\u00edas de servicios en la nube.<\/li>\n<li>Describir las diferencias que hay entre los tipos de inform\u00e1tica en la nube.<\/li>\n<li>Conocer los conceptos b\u00e1sicos de Azure.<\/li>\n<li>Sabr\u00e1 los servicios de Azure.<\/li>\n<li>Utilizar las principales soluciones y herramientas de administraci\u00f3n Azure.<\/li>\n<li>Elegir el mejor servicio de Azure IoT para un determinado escenario empresarial.<\/li>\n<li>Gestionar seguridad con las caracter\u00edsticas ofrecidas en la nube por Microsoft Azure y de seguridad de red.<\/li>\n<li>Configurar las caracter\u00edsticas de identidad, gobernanza, privacidad y cumplimiento.<\/li>\n<li>Conocer los detalles sobre los acuerdos de nivel de servicio y la administraci\u00f3n de costos de Azure.<\/li>\n<li>Elegir el servicio de Azure Artificial Intelligence adecuado para abordar distintos tipos de retos empresariales.<\/li>\n<li>Elegir el servicio de supervisi\u00f3n en la nube adecuado para abordar distintos tipos de retos empresariales.<\/li>\n<\/ul><div><br><\/div>\n<p class=\"rteBlock\">Tenemos la capacidad de poder ajustar este entrenamiento personalizando el contenido de acuerdo a las necesidades de su negocio o empresa. No dude en contactarnos para realizarle una demostraci\u00f3n y podamos entender sus requerimientos para apoyarlo lo mejor posible para que cumpla sus objetivos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46915b04 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"46915b04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/digitnow.com.mx\/es_mx\/cursos-azure\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Quiero saber m\u00e1s!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29ac37cd elementor-widget elementor-widget-image\" data-id=\"29ac37cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"251\" src=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/silverpartner-6d2069f6-6982af26-1920w.png\" class=\"attachment-large size-large wp-image-431\" alt=\"\" srcset=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/silverpartner-6d2069f6-6982af26-1920w.png 550w, https:\/\/digitnow.com.mx\/wp-content\/uploads\/2024\/06\/silverpartner-6d2069f6-6982af26-1920w-300x137.png 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-347b2acc e-con-full e-flex e-con e-parent\" data-id=\"347b2acc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3d155e58 e-con-full e-flex e-con e-child\" data-id=\"3d155e58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ceecf87 elementor-widget elementor-widget-heading\" data-id=\"7ceecf87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obtenga nuestro servicio de Cursos y Capacitaci\u00f3n Empresarial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36fc6405 elementor-widget elementor-widget-text-editor\" data-id=\"36fc6405\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"size-18 m-size-14\" style=\"text-align: center;\"><span class=\"font-size-18 m-font-size-14\">De esta forma, puede aprovechar la experiencia de Digitnow M\u00e9xico para desarrollar su operaci\u00f3n digital, organizaci\u00f3n y capacidades t\u00e9cnicas, para\u00a0 que obtenga beneficios comerciales de forma eficaz, r\u00e1pida y \u00e1gil.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4931fb67 e-con-full e-flex e-con e-child\" data-id=\"4931fb67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46859782 elementor-widget elementor-widget-heading\" data-id=\"46859782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfLe interesa?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56b82b57 elementor-widget elementor-widget-text-editor\" data-id=\"56b82b57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a1Escr\u00edbanos y nos comunicaremos con usted!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f8fe733 elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"2f8fe733\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"142\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"2f8fe733\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"DigitNow\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nombre\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[message]\" id=\"form-field-message\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Tel\u00e9fono\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_876674d elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_876674d]\" id=\"form-field-field_876674d\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Comentarios o dudas\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm elementor-animation-grow\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Cont\u00e1ctenme!<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bffd19e e-flex e-con-boxed e-con e-parent\" data-id=\"bffd19e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conozca nuestros Cursos y planes de Capacitaci\u00f3n Empresarial En Digitnow, ofrecemos Capacitaci\u00f3n Empresarial con un enfoque personalizado para impulsar el crecimiento de su equipo. Nuestros Cursos a la Medida y Cursos por Aplicaci\u00f3n est\u00e1n dise\u00f1ados para satisfacer las necesidades espec\u00edficas de su empresa, asegurando que su personal adquiera las competencias necesarias para enfrentar los desaf\u00edos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":1520,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-142","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacitaci\u00f3n Empresarial - DigitNow<\/title>\n<meta name=\"description\" content=\"Prepare a su talento t\u00e9cnicamente con nuestros servicios de Capacitaci\u00f3n Empresarial. Digitnow le adecua a sus necesidades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digitnow.com.mx\/en\/servicios-2\/cursos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacitaci\u00f3n Empresarial - DigitNow\" \/>\n<meta property=\"og:description\" content=\"Prepare a su talento t\u00e9cnicamente con nuestros servicios de Capacitaci\u00f3n Empresarial. Digitnow le adecua a sus necesidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digitnow.com.mx\/en\/servicios-2\/cursos\/\" \/>\n<meta property=\"og:site_name\" content=\"DigitNow\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DigitNowMexico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T03:31:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DigitNowMexico\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/cursos\\\/\",\"url\":\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/cursos\\\/\",\"name\":\"Capacitaci\u00f3n Empresarial - DigitNow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/cursos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/cursos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digitnow.com.mx\\\/wp-content\\\/uploads\\\/teams-1024x1024.png\",\"datePublished\":\"2024-06-19T04:21:57+00:00\",\"dateModified\":\"2026-03-06T03:31:22+00:00\",\"description\":\"Prepare a su talento t\u00e9cnicamente con nuestros servicios de Capacitaci\u00f3n Empresarial. Digitnow le adecua a sus necesidades.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/cursos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/cursos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/cursos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digitnow.com.mx\\\/wp-content\\\/uploads\\\/teams-1024x1024.png\",\"contentUrl\":\"https:\\\/\\\/digitnow.com.mx\\\/wp-content\\\/uploads\\\/teams-1024x1024.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/cursos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/digitnow.com.mx\\\/es_mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce nuestros servicios\",\"item\":\"https:\\\/\\\/digitnow.com.mx\\\/servicios-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Capacitaci\u00f3n Empresarial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/digitnow.com.mx\\\/\",\"name\":\"Digitnow\",\"description\":\"Soluciones en la nube para empresas\",\"publisher\":{\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digitnow.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/#organization\",\"name\":\"Digitnow\",\"url\":\"https:\\\/\\\/digitnow.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/digitnow.com.mx\\\/wp-content\\\/uploads\\\/logo-digitnow-323w.webp\",\"contentUrl\":\"https:\\\/\\\/digitnow.com.mx\\\/wp-content\\\/uploads\\\/logo-digitnow-323w.webp\",\"width\":320,\"height\":68,\"caption\":\"Digitnow\"},\"image\":{\"@id\":\"https:\\\/\\\/digitnow.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DigitNowMexico\",\"https:\\\/\\\/x.com\\\/DigitNowMexico\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/digitnow\\\/\",\"https:\\\/\\\/www.instagram.com\\\/digitnow_oficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCojoUfDnSdhxh6_VWO1OMGQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacitaci\u00f3n Empresarial - DigitNow","description":"Prepare a su talento t\u00e9cnicamente con nuestros servicios de Capacitaci\u00f3n Empresarial. Digitnow le adecua a sus necesidades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digitnow.com.mx\/en\/servicios-2\/cursos\/","og_locale":"en_US","og_type":"article","og_title":"Capacitaci\u00f3n Empresarial - DigitNow","og_description":"Prepare a su talento t\u00e9cnicamente con nuestros servicios de Capacitaci\u00f3n Empresarial. Digitnow le adecua a sus necesidades.","og_url":"https:\/\/digitnow.com.mx\/en\/servicios-2\/cursos\/","og_site_name":"DigitNow","article_publisher":"https:\/\/www.facebook.com\/DigitNowMexico","article_modified_time":"2026-03-06T03:31:22+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@DigitNowMexico","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/digitnow.com.mx\/servicios-2\/cursos\/","url":"https:\/\/digitnow.com.mx\/servicios-2\/cursos\/","name":"Capacitaci\u00f3n Empresarial - DigitNow","isPartOf":{"@id":"https:\/\/digitnow.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digitnow.com.mx\/servicios-2\/cursos\/#primaryimage"},"image":{"@id":"https:\/\/digitnow.com.mx\/servicios-2\/cursos\/#primaryimage"},"thumbnailUrl":"https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-1024x1024.png","datePublished":"2024-06-19T04:21:57+00:00","dateModified":"2026-03-06T03:31:22+00:00","description":"Prepare a su talento t\u00e9cnicamente con nuestros servicios de Capacitaci\u00f3n Empresarial. Digitnow le adecua a sus necesidades.","breadcrumb":{"@id":"https:\/\/digitnow.com.mx\/servicios-2\/cursos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digitnow.com.mx\/servicios-2\/cursos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digitnow.com.mx\/servicios-2\/cursos\/#primaryimage","url":"https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-1024x1024.png","contentUrl":"https:\/\/digitnow.com.mx\/wp-content\/uploads\/teams-1024x1024.png"},{"@type":"BreadcrumbList","@id":"https:\/\/digitnow.com.mx\/servicios-2\/cursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/digitnow.com.mx\/es_mx\/"},{"@type":"ListItem","position":2,"name":"Conoce nuestros servicios","item":"https:\/\/digitnow.com.mx\/servicios-2\/"},{"@type":"ListItem","position":3,"name":"Capacitaci\u00f3n Empresarial"}]},{"@type":"WebSite","@id":"https:\/\/digitnow.com.mx\/#website","url":"https:\/\/digitnow.com.mx\/","name":"Digitnow","description":"Soluciones en la nube para empresas","publisher":{"@id":"https:\/\/digitnow.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digitnow.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/digitnow.com.mx\/#organization","name":"Digitnow","url":"https:\/\/digitnow.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/digitnow.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/digitnow.com.mx\/wp-content\/uploads\/logo-digitnow-323w.webp","contentUrl":"https:\/\/digitnow.com.mx\/wp-content\/uploads\/logo-digitnow-323w.webp","width":320,"height":68,"caption":"Digitnow"},"image":{"@id":"https:\/\/digitnow.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DigitNowMexico","https:\/\/x.com\/DigitNowMexico","https:\/\/www.linkedin.com\/company\/digitnow\/","https:\/\/www.instagram.com\/digitnow_oficial\/","https:\/\/www.youtube.com\/channel\/UCojoUfDnSdhxh6_VWO1OMGQ"]}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/pages\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/comments?post=142"}],"version-history":[{"count":137,"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/pages\/142\/revisions"}],"predecessor-version":[{"id":5687,"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/pages\/142\/revisions\/5687"}],"up":[{"embeddable":true,"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/pages\/1520"}],"wp:attachment":[{"href":"https:\/\/digitnow.com.mx\/en\/wp-json\/wp\/v2\/media?parent=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}